{"id":8011,"date":"2025-01-28T08:21:40","date_gmt":"2025-01-28T08:21:40","guid":{"rendered":"https:\/\/www.europeanlocpool.com\/?p=8011"},"modified":"2025-01-28T09:16:01","modified_gmt":"2025-01-28T09:16:01","slug":"interview-mit-werner-dampf-retrack-germany-ueber-die-eurodual-und-die-zusammenarbeit-mit-european-loc-pool","status":"publish","type":"post","link":"https:\/\/www.europeanlocpool.com\/de\/interview-mit-werner-dampf-retrack-germany-ueber-die-eurodual-und-die-zusammenarbeit-mit-european-loc-pool\/","title":{"rendered":"Interview mit Werner Dampf, Retrack Germany, \u00fcber die EuroDual und die Zusammenarbeit mit European Loc Pool"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>European Loc Pool (ELP) <\/strong>ist ein Vorreiter in der Bereitstellung von Full-Service-Leasingl\u00f6sungen f\u00fcr den Schieneng\u00fcterverkehr. Der enge Austausch mit unseren Kunden und ihr Feedback sind uns sehr wichtig.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir hatten die Gelegenheit, mit <strong>Werner Dampf<\/strong>, Eisenbahnbetriebsleiter der <strong>Retrack Germany GmbH<\/strong>, \u00fcber seine Erfahrungen mit der EuroDual und die Zusammenarbeit mit ELP zu sprechen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>1. Wie sind Ihre bisherigen Erfahrungen mit der EuroDual und ihrer Leistung in Ihrem Betrieb?<\/strong><br>\u201eAlles begann im Februar 2021, als ich die Gelegenheit hatte, die EuroDual in Braunschweig abzuholen. Ich war bei der \u00dcbergabe sowie der Schulung am Fahrzeug dabei \u2013 ein rundum gelungenes Paket von ELP! <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seit vier Jahren setzen wir die EuroDual bei Retrack ein, und unsere Erfahrungen sind durchweg positiv. Die Lokomotive ist \u00e4u\u00dferst zuverl\u00e4ssig und benutzerfreundlich. Besonders beeindruckend ist ihre Energieeffizienz und Leistungsf\u00e4higkeit. Es ist ein durchdachtes Konzept, das in der Praxis bestens funktioniert. Ein gro\u00dfes Lob auch von unseren Lokf\u00fchrern, die die EuroDual sehr sch\u00e4tzen. Sie ist st\u00f6rungsfrei unterwegs, und das Handling ist relative einfach.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Verbesserungspotenzial? Eigentlich nur Kleinigkeiten, wie ein Aluminiumknopf im F\u00fchrerstand \u2013 aber das ist wirklich Jammern auf hohem Niveau!\u201c<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"898\" height=\"748\" src=\"https:\/\/www.europeanlocpool.com\/wp-content\/uploads\/2025\/01\/image.jpeg\" alt=\"\" class=\"wp-image-8012\" style=\"width:700px\" srcset=\"https:\/\/www.europeanlocpool.com\/wp-content\/uploads\/2025\/01\/image.jpeg 898w, https:\/\/www.europeanlocpool.com\/wp-content\/uploads\/2025\/01\/image-300x250.jpeg 300w, https:\/\/www.europeanlocpool.com\/wp-content\/uploads\/2025\/01\/image-768x640.jpeg 768w\" sizes=\"auto, (max-width: 898px) 100vw, 898px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2. Welche Vorteile oder Herausforderungen sehen Sie im Einsatz der EuroDual in Ihrer Branche?<\/strong><br>\u201eDie EuroDual bietet uns viele Vorteile. Besonders hervorzuheben ist ihre Flexibilit\u00e4t, sowohl im elektrischen als auch im Dieselbetrieb. Diese Unabh\u00e4ngigkeit erm\u00f6glicht uns ein breites Einsatzspektrum. Die Last-Mile-F\u00e4higkeit ist dabei ein entscheidender Vorteil, gerade f\u00fcr Rangierarbeiten an unterschiedlichen Standorten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ihr Haupteinsatzgebiet liegt bei uns im Schwerlastverkehr \u2013 sei es f\u00fcr Mineralien, Kohle, Stahl oder Getreide. Hier spielt die EuroDual ihre volle Leistungsst\u00e4rke aus. Auch im Schrotttransport zeigt sie, wie gut durchdacht ihr Konzept ist. Unsere Lokf\u00fchrer f\u00fchlen sich an Bord der EuroDual rundum wohl, und die Arbeit mit dieser Lok macht einfach Spa\u00df.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Herausforderungen gibt es kaum. Die EuroDual l\u00e4uft zuverl\u00e4ssig und erf\u00fcllt alle Anforderungen. Eine Ausnahme gab es jedoch ganz am Anfang: In Oberhausen West mussten wir einmal manuell AdBlue nachf\u00fcllen \u2013 und das waren 40 Kanister! Eine Geschichte, die man nicht vergisst. Heute k\u00f6nnen wir dank der von ELP bereitgestellten AdBlue-Tankpistolen inzwischen problemlos an DB-Tankstellen auff\u00fcllen, ohne zus\u00e4tzlichen Aufwand.\u201c<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>3. Was sch\u00e4tzen Sie an der Zusammenarbeit mit ELP?<\/strong><br>\u201eDie Zusammenarbeit mit ELP ist gut. Die Kommunikation verl\u00e4uft unkompliziert, und Probleme werden z\u00fcgig und effizient gel\u00f6st. Wir sind zufrieden mit der Zusammenarbeit und freuen uns auf die n\u00e4chsten gemeinsamen Projekte.\u201c<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Wir bedanken uns sehr herzlich bei Werner Dampf und w\u00fcnschen allzeit gute Fahrt!<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1156\" height=\"747\" src=\"https:\/\/www.europeanlocpool.com\/wp-content\/uploads\/2025\/01\/image-1.jpeg\" alt=\"\" class=\"wp-image-8014\" style=\"width:500px\" srcset=\"https:\/\/www.europeanlocpool.com\/wp-content\/uploads\/2025\/01\/image-1.jpeg 1156w, https:\/\/www.europeanlocpool.com\/wp-content\/uploads\/2025\/01\/image-1-300x194.jpeg 300w, https:\/\/www.europeanlocpool.com\/wp-content\/uploads\/2025\/01\/image-1-1024x662.jpeg 1024w, https:\/\/www.europeanlocpool.com\/wp-content\/uploads\/2025\/01\/image-1-768x496.jpeg 768w\" sizes=\"auto, (max-width: 1156px) 100vw, 1156px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Werner Dampf (links) bei der \u00dcbernahme der beiden EuroDual von ELP in Februar 2021<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mehr \u00fcber Hybridlokomotiven<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">European Loc Pool (ELP) konzentriert sich auf innovative sechsachsige Hybridlokomotiven von Stadler und setzt damit neue Standards im europ\u00e4ischen Schieneng\u00fcterverkehr. Die EuroDual und die Euro9000 Lokomotiven revolutionieren mit ihrer Kombination aus Elektro- und Dieselbetrieb den europ\u00e4ischen Schieneng\u00fcterverkehr und erm\u00f6glichen auch reibungslose Last-Mile und Rangieroperationen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Die EuroDual<\/strong>, als Vorreiter im Portfolio von European Loc Pool, ist ein Gamechanger im Schieneng\u00fcterverkehr. Mit ihrer Zugkraft von 500 kN und einer Leistung von bis zu 2,8 MW im Diesel- und 6.2 MW im Elektrobetrieb bietet sie eine um bis zu 40% h\u00f6here Ladekapazit\u00e4t. Die EuroDual ist bereits erfolgreich in Deutschland, \u00d6sterreich, Frankreich und Skandinavien im Einsatz und wurde k\u00fcrzlich in Serbien zugelassen. Slowenien und Kroatien werden im ersten Quartal 2024 folgen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.europeanlocpool.com\/lokomotiven\/eurodual\/\">EuroDualLokomotive | European Loc Pool<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00dcber European Loc Pool AG<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">European Loc Pool (ELP) ist ein f\u00fchrender Anbieter von innovativen Leasing- und Dienstleistungen f\u00fcr Lokomotiven mit Sitz in Frauenfeld, Schweiz. Das Full-Service-Leasingpaket von ELP umfasst pr\u00e4ventive und korrektive Instandhaltung (inklusive Revisionen), abgedeckt mit entsprechenden Verf\u00fcgbarkeits-sowie Zuverl\u00e4ssigkeitsgarantien. Zus\u00e4tzlich bietet ELP Lokf\u00fchrerschulungen und ein auf moderne, sechsachsige Hybridlokomotiven zugeschnittenes, innovatives Versicherungspaket an. Seit der Gr\u00fcndung im Mai 2018 hat ELP 124 Lokomotiven bestellt und davon \u00fcber 100 Lokomotiven verleast und bereits \u00fcber 30 Betreiber in 6 L\u00e4ndern betreut.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Vision von ELP ist es, die europ\u00e4ische Schieneng\u00fcterverkehrsbranche positiv zu disruptieren. Das erfahrene Team von ELP legt gro\u00dfen Wert auf Sicherheit, Zuverl\u00e4ssigkeit, Kosteneffizienz und Nachhaltigkeit, um die Erwartungen der Kunden zu \u00fcbertreffen.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fcr weitere Informationen besuchen Sie bitte unsere <a href=\"https:\/\/www.europeanlocpool.com\/\">Webseite<\/a> oder folgen Sie uns auf <a href=\"http:\/\/www.linkedin.com\/company\/european-loc-pool-ag\">LinkedIn<\/a>, <a href=\"https:\/\/www.instagram.com\/europeanlocpool\/\">Instagram<\/a>, oder <a href=\"https:\/\/www.youtube.com\/@EuropeanLocPool\">YouTube<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<p class=\"wp-block-paragraph\">Pressekontakt European Loc Pool:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Henrike Wilkens<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Marketing &amp; Communications<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">E-mail: Henrike.Wilkens@europeanlocpool.com<\/p>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>European Loc Pool (ELP) ist ein Vorreiter in der Bereitstellung von Full-Service-Leasingl\u00f6sungen f\u00fcr den Schieneng\u00fcterverkehr. Der enge Austausch mit unseren Kunden und ihr Feedback sind uns sehr wichtig. Wir hatten die Gelegenheit, mit Werner Dampf, Eisenbahnbetriebsleiter der Retrack Germany GmbH, \u00fcber seine Erfahrungen mit der EuroDual und die Zusammenarbeit mit ELP zu sprechen. 1. Wie [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":8027,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-8011","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unkategorisiert"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.8 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Interview mit Werner Dampf, Retrack Germany, \u00fcber die EuroDual und die Zusammenarbeit mit European Loc Pool - European Loc Pool<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.europeanlocpool.com\/de\/interview-mit-werner-dampf-retrack-germany-ueber-die-eurodual-und-die-zusammenarbeit-mit-european-loc-pool\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Interview mit Werner Dampf, Retrack Germany, \u00fcber die EuroDual und die Zusammenarbeit mit European Loc Pool\" \/>\n<meta property=\"og:description\" content=\"European Loc Pool (ELP) ist ein Vorreiter in der Bereitstellung von Full-Service-Leasingl\u00f6sungen f\u00fcr den Schieneng\u00fcterverkehr. Der enge Austausch mit unseren Kunden und ihr Feedback sind uns sehr wichtig. Wir hatten die Gelegenheit, mit Werner Dampf, Eisenbahnbetriebsleiter der Retrack Germany GmbH, \u00fcber seine Erfahrungen mit der EuroDual und die Zusammenarbeit mit ELP zu sprechen. 1. Wie [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.europeanlocpool.com\/de\/interview-mit-werner-dampf-retrack-germany-ueber-die-eurodual-und-die-zusammenarbeit-mit-european-loc-pool\/\" \/>\n<meta property=\"og:site_name\" content=\"European Loc Pool\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-28T08:21:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-28T09:16:01+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.europeanlocpool.com\/wp-content\/uploads\/2025\/01\/Customer-voice-3.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"932\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Morena Dinardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Morena Dinardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.europeanlocpool.com\\\/de\\\/interview-mit-werner-dampf-retrack-germany-ueber-die-eurodual-und-die-zusammenarbeit-mit-european-loc-pool\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.europeanlocpool.com\\\/de\\\/interview-mit-werner-dampf-retrack-germany-ueber-die-eurodual-und-die-zusammenarbeit-mit-european-loc-pool\\\/\"},\"author\":{\"name\":\"Morena Dinardo\",\"@id\":\"https:\\\/\\\/www.europeanlocpool.com\\\/#\\\/schema\\\/person\\\/2522527cf653c9575aa7793ef3a571db\"},\"headline\":\"Interview mit Werner Dampf, Retrack Germany, \u00fcber die EuroDual und die Zusammenarbeit mit European Loc Pool\",\"datePublished\":\"2025-01-28T08:21:40+00:00\",\"dateModified\":\"2025-01-28T09:16:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.europeanlocpool.com\\\/de\\\/interview-mit-werner-dampf-retrack-germany-ueber-die-eurodual-und-die-zusammenarbeit-mit-european-loc-pool\\\/\"},\"wordCount\":736,\"publisher\":{\"@id\":\"https:\\\/\\\/www.europeanlocpool.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.europeanlocpool.com\\\/de\\\/interview-mit-werner-dampf-retrack-germany-ueber-die-eurodual-und-die-zusammenarbeit-mit-european-loc-pool\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.europeanlocpool.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Customer-voice-3.png\",\"articleSection\":[\"Unkategorisiert\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.europeanlocpool.com\\\/de\\\/interview-mit-werner-dampf-retrack-germany-ueber-die-eurodual-und-die-zusammenarbeit-mit-european-loc-pool\\\/\",\"url\":\"https:\\\/\\\/www.europeanlocpool.com\\\/de\\\/interview-mit-werner-dampf-retrack-germany-ueber-die-eurodual-und-die-zusammenarbeit-mit-european-loc-pool\\\/\",\"name\":\"Interview mit Werner Dampf, Retrack Germany, \u00fcber die EuroDual und die Zusammenarbeit mit European Loc Pool - European Loc Pool\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.europeanlocpool.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.europeanlocpool.com\\\/de\\\/interview-mit-werner-dampf-retrack-germany-ueber-die-eurodual-und-die-zusammenarbeit-mit-european-loc-pool\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.europeanlocpool.com\\\/de\\\/interview-mit-werner-dampf-retrack-germany-ueber-die-eurodual-und-die-zusammenarbeit-mit-european-loc-pool\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.europeanlocpool.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Customer-voice-3.png\",\"datePublished\":\"2025-01-28T08:21:40+00:00\",\"dateModified\":\"2025-01-28T09:16:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.europeanlocpool.com\\\/de\\\/interview-mit-werner-dampf-retrack-germany-ueber-die-eurodual-und-die-zusammenarbeit-mit-european-loc-pool\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.europeanlocpool.com\\\/de\\\/interview-mit-werner-dampf-retrack-germany-ueber-die-eurodual-und-die-zusammenarbeit-mit-european-loc-pool\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.europeanlocpool.com\\\/de\\\/interview-mit-werner-dampf-retrack-germany-ueber-die-eurodual-und-die-zusammenarbeit-mit-european-loc-pool\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.europeanlocpool.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Customer-voice-3.png\",\"contentUrl\":\"https:\\\/\\\/www.europeanlocpool.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Customer-voice-3.png\",\"width\":1800,\"height\":932},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.europeanlocpool.com\\\/de\\\/interview-mit-werner-dampf-retrack-germany-ueber-die-eurodual-und-die-zusammenarbeit-mit-european-loc-pool\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.europeanlocpool.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Interview mit Werner Dampf, Retrack Germany, \u00fcber die EuroDual und die Zusammenarbeit mit European Loc Pool\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.europeanlocpool.com\\\/#website\",\"url\":\"https:\\\/\\\/www.europeanlocpool.com\\\/\",\"name\":\"European Loc Pool\",\"description\":\"Passion for traction\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.europeanlocpool.com\\\/#organization\"},\"alternateName\":\"ELP\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.europeanlocpool.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.europeanlocpool.com\\\/#organization\",\"name\":\"European Loc Pool\",\"alternateName\":\"ELP\",\"url\":\"https:\\\/\\\/www.europeanlocpool.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.europeanlocpool.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.europeanlocpool.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/MyELP_image_light.png\",\"contentUrl\":\"https:\\\/\\\/www.europeanlocpool.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/MyELP_image_light.png\",\"width\":1720,\"height\":820,\"caption\":\"European Loc Pool\"},\"image\":{\"@id\":\"https:\\\/\\\/www.europeanlocpool.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/european-loc-pool\\\/\",\"https:\\\/\\\/www.instagram.com\\\/europeanlocpool\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@EuropeanLocPool\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.europeanlocpool.com\\\/#\\\/schema\\\/person\\\/2522527cf653c9575aa7793ef3a571db\",\"name\":\"Morena Dinardo\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Interview mit Werner Dampf, Retrack Germany, \u00fcber die EuroDual und die Zusammenarbeit mit European Loc Pool - European Loc Pool","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.europeanlocpool.com\/de\/interview-mit-werner-dampf-retrack-germany-ueber-die-eurodual-und-die-zusammenarbeit-mit-european-loc-pool\/","og_locale":"de_DE","og_type":"article","og_title":"Interview mit Werner Dampf, Retrack Germany, \u00fcber die EuroDual und die Zusammenarbeit mit European Loc Pool","og_description":"European Loc Pool (ELP) ist ein Vorreiter in der Bereitstellung von Full-Service-Leasingl\u00f6sungen f\u00fcr den Schieneng\u00fcterverkehr. Der enge Austausch mit unseren Kunden und ihr Feedback sind uns sehr wichtig. Wir hatten die Gelegenheit, mit Werner Dampf, Eisenbahnbetriebsleiter der Retrack Germany GmbH, \u00fcber seine Erfahrungen mit der EuroDual und die Zusammenarbeit mit ELP zu sprechen. 1. Wie [&hellip;]","og_url":"https:\/\/www.europeanlocpool.com\/de\/interview-mit-werner-dampf-retrack-germany-ueber-die-eurodual-und-die-zusammenarbeit-mit-european-loc-pool\/","og_site_name":"European Loc Pool","article_published_time":"2025-01-28T08:21:40+00:00","article_modified_time":"2025-01-28T09:16:01+00:00","og_image":[{"width":1800,"height":932,"url":"http:\/\/www.europeanlocpool.com\/wp-content\/uploads\/2025\/01\/Customer-voice-3.png","type":"image\/png"}],"author":"Morena Dinardo","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Morena Dinardo","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.europeanlocpool.com\/de\/interview-mit-werner-dampf-retrack-germany-ueber-die-eurodual-und-die-zusammenarbeit-mit-european-loc-pool\/#article","isPartOf":{"@id":"https:\/\/www.europeanlocpool.com\/de\/interview-mit-werner-dampf-retrack-germany-ueber-die-eurodual-und-die-zusammenarbeit-mit-european-loc-pool\/"},"author":{"name":"Morena Dinardo","@id":"https:\/\/www.europeanlocpool.com\/#\/schema\/person\/2522527cf653c9575aa7793ef3a571db"},"headline":"Interview mit Werner Dampf, Retrack Germany, \u00fcber die EuroDual und die Zusammenarbeit mit European Loc Pool","datePublished":"2025-01-28T08:21:40+00:00","dateModified":"2025-01-28T09:16:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.europeanlocpool.com\/de\/interview-mit-werner-dampf-retrack-germany-ueber-die-eurodual-und-die-zusammenarbeit-mit-european-loc-pool\/"},"wordCount":736,"publisher":{"@id":"https:\/\/www.europeanlocpool.com\/#organization"},"image":{"@id":"https:\/\/www.europeanlocpool.com\/de\/interview-mit-werner-dampf-retrack-germany-ueber-die-eurodual-und-die-zusammenarbeit-mit-european-loc-pool\/#primaryimage"},"thumbnailUrl":"https:\/\/www.europeanlocpool.com\/wp-content\/uploads\/2025\/01\/Customer-voice-3.png","articleSection":["Unkategorisiert"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.europeanlocpool.com\/de\/interview-mit-werner-dampf-retrack-germany-ueber-die-eurodual-und-die-zusammenarbeit-mit-european-loc-pool\/","url":"https:\/\/www.europeanlocpool.com\/de\/interview-mit-werner-dampf-retrack-germany-ueber-die-eurodual-und-die-zusammenarbeit-mit-european-loc-pool\/","name":"Interview mit Werner Dampf, Retrack Germany, \u00fcber die EuroDual und die Zusammenarbeit mit European Loc Pool - European Loc Pool","isPartOf":{"@id":"https:\/\/www.europeanlocpool.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.europeanlocpool.com\/de\/interview-mit-werner-dampf-retrack-germany-ueber-die-eurodual-und-die-zusammenarbeit-mit-european-loc-pool\/#primaryimage"},"image":{"@id":"https:\/\/www.europeanlocpool.com\/de\/interview-mit-werner-dampf-retrack-germany-ueber-die-eurodual-und-die-zusammenarbeit-mit-european-loc-pool\/#primaryimage"},"thumbnailUrl":"https:\/\/www.europeanlocpool.com\/wp-content\/uploads\/2025\/01\/Customer-voice-3.png","datePublished":"2025-01-28T08:21:40+00:00","dateModified":"2025-01-28T09:16:01+00:00","breadcrumb":{"@id":"https:\/\/www.europeanlocpool.com\/de\/interview-mit-werner-dampf-retrack-germany-ueber-die-eurodual-und-die-zusammenarbeit-mit-european-loc-pool\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.europeanlocpool.com\/de\/interview-mit-werner-dampf-retrack-germany-ueber-die-eurodual-und-die-zusammenarbeit-mit-european-loc-pool\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.europeanlocpool.com\/de\/interview-mit-werner-dampf-retrack-germany-ueber-die-eurodual-und-die-zusammenarbeit-mit-european-loc-pool\/#primaryimage","url":"https:\/\/www.europeanlocpool.com\/wp-content\/uploads\/2025\/01\/Customer-voice-3.png","contentUrl":"https:\/\/www.europeanlocpool.com\/wp-content\/uploads\/2025\/01\/Customer-voice-3.png","width":1800,"height":932},{"@type":"BreadcrumbList","@id":"https:\/\/www.europeanlocpool.com\/de\/interview-mit-werner-dampf-retrack-germany-ueber-die-eurodual-und-die-zusammenarbeit-mit-european-loc-pool\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.europeanlocpool.com\/de\/"},{"@type":"ListItem","position":2,"name":"Interview mit Werner Dampf, Retrack Germany, \u00fcber die EuroDual und die Zusammenarbeit mit European Loc Pool"}]},{"@type":"WebSite","@id":"https:\/\/www.europeanlocpool.com\/#website","url":"https:\/\/www.europeanlocpool.com\/","name":"European Loc Pool","description":"Passion for traction","publisher":{"@id":"https:\/\/www.europeanlocpool.com\/#organization"},"alternateName":"ELP","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.europeanlocpool.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.europeanlocpool.com\/#organization","name":"European Loc Pool","alternateName":"ELP","url":"https:\/\/www.europeanlocpool.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.europeanlocpool.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.europeanlocpool.com\/wp-content\/uploads\/2024\/09\/MyELP_image_light.png","contentUrl":"https:\/\/www.europeanlocpool.com\/wp-content\/uploads\/2024\/09\/MyELP_image_light.png","width":1720,"height":820,"caption":"European Loc Pool"},"image":{"@id":"https:\/\/www.europeanlocpool.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/european-loc-pool\/","https:\/\/www.instagram.com\/europeanlocpool\/","https:\/\/www.youtube.com\/@EuropeanLocPool"]},{"@type":"Person","@id":"https:\/\/www.europeanlocpool.com\/#\/schema\/person\/2522527cf653c9575aa7793ef3a571db","name":"Morena Dinardo"}]}},"_links":{"self":[{"href":"https:\/\/www.europeanlocpool.com\/de\/wp-json\/wp\/v2\/posts\/8011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europeanlocpool.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europeanlocpool.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europeanlocpool.com\/de\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europeanlocpool.com\/de\/wp-json\/wp\/v2\/comments?post=8011"}],"version-history":[{"count":2,"href":"https:\/\/www.europeanlocpool.com\/de\/wp-json\/wp\/v2\/posts\/8011\/revisions"}],"predecessor-version":[{"id":8105,"href":"https:\/\/www.europeanlocpool.com\/de\/wp-json\/wp\/v2\/posts\/8011\/revisions\/8105"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europeanlocpool.com\/de\/wp-json\/wp\/v2\/media\/8027"}],"wp:attachment":[{"href":"https:\/\/www.europeanlocpool.com\/de\/wp-json\/wp\/v2\/media?parent=8011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europeanlocpool.com\/de\/wp-json\/wp\/v2\/categories?post=8011"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europeanlocpool.com\/de\/wp-json\/wp\/v2\/tags?post=8011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}